{"id":12708,"date":"2024-02-08T14:35:27","date_gmt":"2024-02-08T14:35:27","guid":{"rendered":"https:\/\/introspect.ca\/2024\/02\/08\/meet-us-at-techfair-the-mcgill-university-engineering-technology-career-fair\/"},"modified":"2026-07-10T19:57:26","modified_gmt":"2026-07-10T19:57:26","slug":"meet-us-at-techfair-the-mcgill-university-engineering-technology-career-fair","status":"publish","type":"post","link":"https:\/\/introspect.ca\/fr\/2024\/02\/08\/meet-us-at-techfair-the-mcgill-university-engineering-technology-career-fair\/","title":{"rendered":"Venez nous rencontrer au TechFair : le salon de l&#8217;emploi en ing\u00e9nierie et technologie de l&rsquo;Universit\u00e9 McGill"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><strong>Date<\/strong>: jeudi 8 f\u00e9vrier 2024<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Horaires :<\/strong> de 10 h \u00e0 15 h (heure de l&rsquo;Est) <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Lieu :<\/strong> Nouvelle r\u00e9sidence universitaire McGill, 3625, avenue Park, Montr\u00e9al (Qu\u00e9bec) H2X 3P8<\/span><\/p>\n<h3><strong>Aper\u00e7u : <\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">En tant que leader dans la fabrication d&rsquo;outils de test et de mesure destin\u00e9s aux applications num\u00e9riques \u00e0 haut d\u00e9bit, Introspect Technology souhaite renforcer son \u00e9quipe de professionnels \u00e0 temps plein dans les domaines de l&rsquo;ing\u00e9nierie \u00e9lectrique, mat\u00e9rielle et logicielle. Nous sommes \u00e9galement impatients de collaborer avec notre prochaine promotion de stagiaires d&rsquo;\u00e9t\u00e9. L&rsquo;environnement chez Introspect vous offre la possibilit\u00e9 de r\u00e9aliser votre plein potentiel et de produire le meilleur travail de votre <\/span><a href=\"https:\/\/introspect.ca\/fr\/careers\/\"><span style=\"font-weight: 400;\">carri\u00e8re<\/span><\/a><span style=\"font-weight: 400;\">et d&rsquo;apporter une valeur ajout\u00e9e significative \u00e0 des clients de renom dans le secteur des technologies. Nous sommes convaincus que votre impact sur le monde est <\/span><i><span style=\"font-weight: 400;\">illimit\u00e9. <\/span><\/i><span style=\"font-weight: 400;\">Le <\/span><a href=\"https:\/\/www.mcgill.ca\/careers4engineers\/techfair\/students\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Salon de l&#8217;emploi en ing\u00e9nierie et technologie de l&rsquo;Universit\u00e9 McGill<\/span><\/a><span style=\"font-weight: 400;\"> est l&rsquo;occasion id\u00e9ale de postuler en personne et de nous poser toutes vos questions sur le travail chez Introspect Technology.<\/span><\/p>\n<h3><strong>\u00c0 qui s&rsquo;adresse cet \u00e9v\u00e9nement :<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La TechFair est r\u00e9serv\u00e9e aux \u00e9tudiants actuellement inscrits \u00e0 l&rsquo;Universit\u00e9 McGill (de premier cycle et de deuxi\u00e8me et troisi\u00e8me cycles) ainsi qu&rsquo;aux anciens \u00e9l\u00e8ves. Les participants doivent pr\u00e9senter leur carte d&rsquo;\u00e9tudiant de McGill. <\/span><\/p>\n<h3><strong>Pr\u00e9sence introspective :<\/strong><\/h3>\n<p>Faites connaissance avec certains membres de l&rsquo;\u00e9quipe technique d&rsquo;Introspect afin de vous faire une premi\u00e8re id\u00e9e de ce qu&rsquo;est le travail au sein de cette \u00e9quipe innovante.<\/p>\n<h3><strong>Inscription :<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Il n&rsquo;est pas n\u00e9cessaire de s&rsquo;inscrire. Il vous suffit de vous pr\u00e9senter \u00e0 la nouvelle r\u00e9sidence universitaire de McGill muni de votre carte d&rsquo;\u00e9tudiant McGill. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 f\u00e9vrier 2024<\/p>\n","protected":false},"author":19,"featured_media":5870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1740],"tags":[1938,1939,1940],"class_list":["post-12708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","tag-careers","tag-hiring","tag-internship"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/comments?post=12708"}],"version-history":[{"count":1,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12708\/revisions"}],"predecessor-version":[{"id":12709,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12708\/revisions\/12709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/media\/5870"}],"wp:attachment":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/media?parent=12708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/categories?post=12708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/tags?post=12708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}