{"id":12689,"date":"2025-01-07T07:05:03","date_gmt":"2025-01-07T07:05:03","guid":{"rendered":"https:\/\/introspect.ca\/2025\/01\/07\/probing-ddr5-and-lpddr5-signals\/"},"modified":"2026-07-10T20:25:32","modified_gmt":"2026-07-10T20:25:32","slug":"probing-ddr5-and-lpddr5-signals","status":"publish","type":"post","link":"https:\/\/introspect.ca\/fr\/2025\/01\/07\/probing-ddr5-and-lpddr5-signals\/","title":{"rendered":"Analyse des signaux DDR5 et LPDDR5"},"content":{"rendered":"<p><strong>Titre :<\/strong> Analyse des signaux DDR5 et LPDDR5<br \/>\n<strong>Date :<\/strong> 25 f\u00e9vrier 2025<br \/>\n<strong>Heure :<\/strong> 11 h (heure de l&rsquo;Est) \/ 17 h (heure d&rsquo;Europe centrale)  <\/p>\n<h3>Vue d&rsquo;ensemble<\/h3>\n<p>Saviez-vous que vous pouvez utiliser <a href=\"https:\/\/introspect.ca\/fr\/product\/rsh2-remote-sampling-head\/\" target=\"_blank\" rel=\"noopener\">les t\u00eates de sondage \u00e0 distance<\/a> d&rsquo;Introspect pour analyser les signaux DDR5 et LPDDR5 ? Ces solutions de sondes actives polyvalentes ne sont pas seulement utiles pour se connecter \u00e0 l&rsquo;analyseur de protocole d&rsquo;Introspect, mais elles sont \u00e9galement compatibles avec tous vos oscilloscopes \u00e0 large bande passante pr\u00e9f\u00e9r\u00e9s. Rejoignez-nous pour ce webinaire gratuit afin de d\u00e9couvrir les d\u00e9fis et les solutions permettant de tester de mani\u00e8re fiable et pr\u00e9cise les interfaces m\u00e9moire de nouvelle g\u00e9n\u00e9ration.  <\/p>\n<h3>Ordre du jour<\/h3>\n<ul>\n<li>Bref aper\u00e7u des interfaces m\u00e9moire DDR et LPDDR<\/li>\n<li>Les d\u00e9fis du test par sonde<br \/>\n\u25cb Pourquoi tester les signaux DDR ?<br \/>\n\u25cb Quels signaux faut-il tester ?<\/li>\n<li>D\u00e9bogage du protocole<\/li>\n<li>Mesure des signaux et conformit\u00e9<\/li>\n<\/ul>\n<h3>Pourquoi cet \u00e9v\u00e9nement est-il important ?<\/h3>\n<p>Alors que les normes DDR5 et LPDDR5 atteignent des vitesses fulgurantes, la conception des contr\u00f4leurs et des syst\u00e8mes de m\u00e9moire devient extr\u00eamement complexe. Les effets de d\u00e9gradation du signal peuvent facilement compromettre les performances, et les fonctionnalit\u00e9s des protocoles d\u00e9pendent de plus en plus de l&rsquo;int\u00e9grit\u00e9 du signal. Il existe donc un besoin crucial de tester les signaux DDR, non seulement pour v\u00e9rifier la conformit\u00e9 \u00e9lectrique, mais aussi pour le d\u00e9bogage des protocoles et la validation de la conception.  <\/p>\n<h3>\u00c0 qui s&rsquo;adresse cette formation ?<\/h3>\n<p>Ing\u00e9nieurs ASIC, ing\u00e9nieurs en conception num\u00e9rique, ing\u00e9nieurs en conception analogique, ing\u00e9nieurs en v\u00e9rification, ing\u00e9nieurs produit, ing\u00e9nieurs d&rsquo;essais, ing\u00e9nieurs d&rsquo;application, int\u00e9grateurs de syst\u00e8mes, responsables de gamme de produits et chefs de projet.<\/p>\n<h3><strong>\u00c0 propos de notre conf\u00e9rencier<\/strong><\/h3>\n<p>Pionnier du secteur des tests, le Dr Mohamed Hafed est le fondateur et directeur g\u00e9n\u00e9ral d\u2019Introspect Technology. En tant qu\u2019inventeur principal de plusieurs brevets li\u00e9s aux tests et \u00e0 la mesure de l\u2019int\u00e9grit\u00e9 du signal, le Dr Hafed est \u00e0 la t\u00eate d\u2019Introspect depuis 2012, faisant de l\u2019entreprise le premier fabricant d\u2019outils de test et de mesure pour les applications num\u00e9riques \u00e0 haut d\u00e9bit. Aujourd&rsquo;hui, il dirige l&rsquo;\u00e9quipe d&rsquo;Introspect afin qu&rsquo;elle r\u00e9alise les meilleures performances de sa carri\u00e8re et repousse les limites du possible dans les domaines du DDR, du MIPI, du DisplayPort et de nombreuses autres sp\u00e9cifications.  <\/p>\n<h3>Regardez le webinaire<\/h3>\n<p><a href=\"https:\/\/attendee.gotowebinar.com\/register\/2652747068866962008?source=Event+Web+Page\" target=\"_blank\" rel=\"noopener\">Cliquez ici pour visionner l&rsquo;enregistrement.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 f\u00e9vrier 2025<\/p>\n","protected":false},"author":19,"featured_media":10174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1740],"tags":[1932,1933,1934,1935],"class_list":["post-12689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","tag-ddr5","tag-lpddr5","tag-signal-probing","tag-webinar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/comments?post=12689"}],"version-history":[{"count":1,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12689\/revisions"}],"predecessor-version":[{"id":12690,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/posts\/12689\/revisions\/12690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/media\/10174"}],"wp:attachment":[{"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/media?parent=12689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/categories?post=12689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/introspect.ca\/fr\/wp-json\/wp\/v2\/tags?post=12689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}